{"id":419534,"date":"2022-07-31T04:04:03","date_gmt":"2022-07-31T08:04:03","guid":{"rendered":"https:\/\/erickimphotography.com\/blog\/?p=419534"},"modified":"2022-07-31T04:04:03","modified_gmt":"2022-07-31T08:04:03","slug":"pacification-is-bad","status":"publish","type":"post","link":"https:\/\/erickimphotography.com\/blog\/2022\/07\/31\/pacification-is-bad\/","title":{"rendered":"PACIFICATION IS BAD."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[17],"tags":[],"class_list":["post-419534","post","type-post","status-publish","format-standard","hentry","category-posts"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/erickimphotography.com\/blog\/wp-json\/wp\/v2\/posts\/419534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/erickimphotography.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/erickimphotography.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/erickimphotography.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/erickimphotography.com\/blog\/wp-json\/wp\/v2\/comments?post=419534"}],"version-history":[{"count":1,"href":"https:\/\/erickimphotography.com\/blog\/wp-json\/wp\/v2\/posts\/419534\/revisions"}],"predecessor-version":[{"id":419535,"href":"https:\/\/erickimphotography.com\/blog\/wp-json\/wp\/v2\/posts\/419534\/revisions\/419535"}],"wp:attachment":[{"href":"https:\/\/erickimphotography.com\/blog\/wp-json\/wp\/v2\/media?parent=419534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/erickimphotography.com\/blog\/wp-json\/wp\/v2\/categories?post=419534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/erickimphotography.com\/blog\/wp-json\/wp\/v2\/tags?post=419534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}